{"id":10000752,"date":"2023-08-02T15:28:09","date_gmt":"2023-08-02T22:28:09","guid":{"rendered":"http:\/\/kidworksoc.org\/event\/dia-de-la-carrera-profesional\/"},"modified":"2023-08-02T15:28:09","modified_gmt":"2023-08-02T22:28:09","slug":"dia-de-la-carrera-profesional","status":"publish","type":"tribe_events","link":"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/","title":{"rendered":"D\u00eda de la Carrera Profesional"},"content":{"rendered":"<p>Una vez al mes, los socios hablar\u00e1n de su carrera con los j\u00f3venes de KidWorks. Si est\u00e1 interesado en hacer una presentaci\u00f3n a nuestros estudiantes, env\u00ede un correo electr\u00f3nico a Clarisa.vargas@kidworksoc.org.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una vez al mes, los socios hablar\u00e1n de su carrera con los j\u00f3venes de KidWorks. Si est\u00e1 interesado en hacer una presentaci\u00f3n a nuestros estudiantes, env\u00ede un correo electr\u00f3nico a&hellip; <a class=\"more-link\" href=\"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/\">Siga Leyendo<\/a><\/p>\n","protected":false},"author":6,"featured_media":3368,"template":"","meta":{"_acf_changed":false,"_searchwp_excluded":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-10000752","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda de la Carrera Profesional - KidWorks<\/title>\n<meta name=\"description\" content=\"Una vez al mes, los socios hablar\u00e1n de su carrera con los j\u00f3venes de KidWorks. Si est\u00e1 interesado en hacer una presentaci\u00f3n a nuestros estudiantes, env\u00ede\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda de la Carrera Profesional - KidWorks\" \/>\n<meta property=\"og:description\" content=\"Una vez al mes, los socios hablar\u00e1n de su carrera con los j\u00f3venes de KidWorks. Si est\u00e1 interesado en hacer una presentaci\u00f3n a nuestros estudiantes, env\u00ede\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/\" \/>\n<meta property=\"og:site_name\" content=\"KidWorks\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kidworkscdc\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/08\/wdcxVNEk-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@kidworks\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/event\\\/dia-de-la-carrera-profesional\\\/2024-03-19\\\/\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/event\\\/dia-de-la-carrera-profesional\\\/2024-03-19\\\/\",\"name\":\"D\u00eda de la Carrera Profesional - KidWorks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/event\\\/dia-de-la-carrera-profesional\\\/2024-03-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/event\\\/dia-de-la-carrera-profesional\\\/2024-03-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/wdcxVNEk-scaled.jpeg\",\"datePublished\":\"2023-08-02T22:28:09+00:00\",\"description\":\"Una vez al mes, los socios hablar\u00e1n de su carrera con los j\u00f3venes de KidWorks. Si est\u00e1 interesado en hacer una presentaci\u00f3n a nuestros estudiantes, env\u00ede\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/event\\\/dia-de-la-carrera-profesional\\\/2024-03-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kidworksoc.org\\\/es\\\/event\\\/dia-de-la-carrera-profesional\\\/2024-03-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/event\\\/dia-de-la-carrera-profesional\\\/2024-03-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/wdcxVNEk-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/wdcxVNEk-scaled.jpeg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/event\\\/dia-de-la-carrera-profesional\\\/2024-03-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00eda de la Carrera Profesional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\",\"name\":\"KidWorks\",\"description\":\"Unleashing Youth Potential\u2122\",\"publisher\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#organization\",\"name\":\"KidWorks\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/kidworks-anniversary-logo.png\",\"contentUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/kidworks-anniversary-logo.png\",\"width\":420,\"height\":114,\"caption\":\"KidWorks\"},\"image\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kidworkscdc\",\"https:\\\/\\\/x.com\\\/kidworks\",\"https:\\\/\\\/www.instagram.com\\\/kidworks\\\/\",\"https:\\\/\\\/www.yelp.com\\\/biz\\\/kidworks-santa-ana?osq=kidworks\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/KidWorksCDC\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kidworkscdc\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda de la Carrera Profesional - KidWorks","description":"Una vez al mes, los socios hablar\u00e1n de su carrera con los j\u00f3venes de KidWorks. Si est\u00e1 interesado en hacer una presentaci\u00f3n a nuestros estudiantes, env\u00ede","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00eda de la Carrera Profesional - KidWorks","og_description":"Una vez al mes, los socios hablar\u00e1n de su carrera con los j\u00f3venes de KidWorks. Si est\u00e1 interesado en hacer una presentaci\u00f3n a nuestros estudiantes, env\u00ede","og_url":"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/","og_site_name":"KidWorks","article_publisher":"https:\/\/www.facebook.com\/kidworkscdc","og_image":[{"width":1920,"height":2560,"url":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/08\/wdcxVNEk-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@kidworks","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/","url":"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/","name":"D\u00eda de la Carrera Profesional - KidWorks","isPartOf":{"@id":"https:\/\/kidworksoc.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/#primaryimage"},"image":{"@id":"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/#primaryimage"},"thumbnailUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/08\/wdcxVNEk-scaled.jpeg","datePublished":"2023-08-02T22:28:09+00:00","description":"Una vez al mes, los socios hablar\u00e1n de su carrera con los j\u00f3venes de KidWorks. Si est\u00e1 interesado en hacer una presentaci\u00f3n a nuestros estudiantes, env\u00ede","breadcrumb":{"@id":"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/#primaryimage","url":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/08\/wdcxVNEk-scaled.jpeg","contentUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/08\/wdcxVNEk-scaled.jpeg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/kidworksoc.org\/es\/event\/dia-de-la-carrera-profesional\/2024-03-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kidworksoc.org\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/kidworksoc.org\/es\/events\/"},{"@type":"ListItem","position":3,"name":"D\u00eda de la Carrera Profesional"}]},{"@type":"WebSite","@id":"https:\/\/kidworksoc.org\/es\/#website","url":"https:\/\/kidworksoc.org\/es\/","name":"KidWorks","description":"Unleashing Youth Potential\u2122","publisher":{"@id":"https:\/\/kidworksoc.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kidworksoc.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kidworksoc.org\/es\/#organization","name":"KidWorks","url":"https:\/\/kidworksoc.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kidworksoc.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/01\/kidworks-anniversary-logo.png","contentUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/01\/kidworks-anniversary-logo.png","width":420,"height":114,"caption":"KidWorks"},"image":{"@id":"https:\/\/kidworksoc.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kidworkscdc","https:\/\/x.com\/kidworks","https:\/\/www.instagram.com\/kidworks\/","https:\/\/www.yelp.com\/biz\/kidworks-santa-ana?osq=kidworks","https:\/\/www.youtube.com\/user\/KidWorksCDC","https:\/\/www.linkedin.com\/company\/kidworkscdc"]}]}},"_links":{"self":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/tribe_events\/10000752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":0,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/tribe_events\/10000752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/media\/3368"}],"wp:attachment":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/media?parent=10000752"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/tags?post=10000752"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=10000752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}