{"id":5041,"date":"2024-02-01T13:43:47","date_gmt":"2024-02-01T21:43:47","guid":{"rendered":"https:\/\/kidworksoc.org\/febrero-2024-voluntario-del-mes-ed-duong\/"},"modified":"2024-02-06T15:59:09","modified_gmt":"2024-02-06T23:59:09","slug":"febrero-2024-voluntario-del-mes-ed-duong","status":"publish","type":"post","link":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/","title":{"rendered":"Febrero 2024 &#8216;Voluntario del Mes&#8217;: Ed Duong"},"content":{"rendered":"\n<p>Los alumnos de segundo curso de los programas extraescolares de KidWorks saben que Ed Duong, nuestro \u00abVoluntario del mes\u00bb de febrero de 2024, es el tipo al que acudir cuando se trata de cualquier cosa, desde ayudar con un complicado problema de matem\u00e1ticas hasta calentar en el microondas sus bocadillos de nuggets de pollo a la temperatura adecuada.<\/p>\n\n<p>Ed trabaja como voluntario 16 horas a la semana (de lunes a jueves) con alumnos de segundo y octavo curso, adem\u00e1s de colaborar en nuestros actos y actividades de extensi\u00f3n comunitaria. Tambi\u00e9n ayuda con los estudiantes de secundaria cuando es necesario.<\/p>\n\n<p>\u00abEd tiene un carisma excelente con los estudiantes\u00bb, dice Rosie Estrada, Asistente del Programa. \u00abEs como su mejor amigo. Tiene una mentalidad muy abierta y siempre encuentra soluciones cuando los alumnos necesitan apoyo adicional con determinadas asignaturas. Ed tiene como prioridad ayudar a todos de la mejor manera posible\u00bb.<\/p>\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"1600\" height=\"1067\" src=\"http:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1911-1600x1067.jpg\" alt=\"\" class=\"wp-image-4963 size-full\" srcset=\"https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1911-1600x1067.jpg 1600w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1911-1280x853.jpg 1280w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1911-1440x960.jpg 1440w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1911-1536x1024.jpg 1536w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1911-2048x1365.jpg 2048w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1911-600x400.jpg 600w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Ed ha donado m\u00e1s de 200 horas de su tiempo desde que empez\u00f3 como voluntario en enero de 2020, con un par\u00e9ntesis cuando la pandemia puso en suspenso los programas presenciales.<\/p>\n\n\n\n<p>Descubri\u00f3 KidWorks a trav\u00e9s de una b\u00fasqueda en Internet, ya que anteriormente hab\u00eda trabajado como voluntario en comedores sociales y en campa\u00f1as de recogida de alimentos, pero buscaba una experiencia diferente.<\/p>\n<\/div><\/div>\n\n<p>\u00abQuer\u00eda trabajar con j\u00f3venes de barrios desfavorecidos de una forma que tuviera impacto\u00bb, dice Ed.<\/p>\n\n<p>\u00abEstablecer buenos h\u00e1bitos cuando alguien a\u00fan es joven y destacar su potencial ayuda a animarle a seguir esforz\u00e1ndose por alcanzar el \u00e9xito\u00bb.<\/p>\n\n<p>Ed se gradu\u00f3 en la UCLA en 2023 con una licenciatura en biolog\u00eda molecular, celular y del desarrollo con especializaci\u00f3n en investigaci\u00f3n biom\u00e9dica.<\/p>\n\n<p>Piensa estudiar medicina y mantiene la mente abierta a una especializaci\u00f3n, como ser oftalm\u00f3logo o m\u00e9dico especialista en medicina f\u00edsica y rehabilitaci\u00f3n.  <\/p>\n\n<p>\u00abEd es un voluntario excepcional\u00bb, afirma Vanessa Hern\u00e1ndez, nuestra Directora de Voluntarios. \u00abAporta tanta positividad a nuestros programas extraescolares, junto con alegr\u00eda y risas a eventos como los Fun Fridays, Youth Feast y Youth Lock-in\u00bb.<\/p>\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p>Vanessa a\u00f1ade: \u00abSu cordialidad y su af\u00e1n por ayudar donde haga falta son realmente edificantes. La extraordinaria dedicaci\u00f3n de Ed refleja su genuina preocupaci\u00f3n por cada alumno. Somos muy afortunados de contar con un voluntario tan excepcional en nuestro equipo.\u00bb<\/p>\n\n\n\n<p>Rachel Cervantes, nuestra Coordinadora de Voluntarios, dice que Ed \u00abha sido un voluntario incre\u00edblemente constante y fiable que siempre va m\u00e1s all\u00e1 para asegurarse de que los estudiantes y el personal tengan el apoyo que necesitan.\u00bb<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"1600\" height=\"1067\" src=\"http:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1906-edited-1600x1067.jpg\" alt=\"\" class=\"wp-image-4967 size-full\" srcset=\"https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1906-edited-1600x1067.jpg 1600w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1906-edited-1280x853.jpg 1280w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1906-edited-1440x960.jpg 1440w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1906-edited-1536x1024.jpg 1536w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1906-edited-2048x1365.jpg 2048w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1906-edited-600x400.jpg 600w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure><\/div>\n\n<p>Nuestro \u00abVoluntario del mes\u00bb de febrero es muy intencionado y reflexivo sobre todos los aspectos del voluntariado, incluida la forma de enfocar la ayuda con los deberes para maximizar el potencial de aprendizaje.<\/p>\n\n<p>\u00abPrefiero ayudar a los alumnos a resolver el trabajo por s\u00ed mismos en lugar de decirles directamente las respuestas\u00bb, dice Ed. \u00abPor ejemplo, lo consigo alternando la lectura de un problema y haciendo que ellos lo lean. Tambi\u00e9n reviso dos veces su trabajo, se\u00f1alo sus errores y les pregunto c\u00f3mo pueden solucionarlos.\u00bb<\/p>\n\n<p>Ed a\u00f1ade: \u00abFomento el uso de herramientas como el \u00e1baco o el conteo con los dedos para las matem\u00e1ticas. A los alumnos mayores les ayudo mostr\u00e1ndoles c\u00f3mo hacer o plantear un problema y luego les pido que lo hagan. Si necesitan m\u00e1s ayuda, siempre les pregunto cu\u00e1l debe ser el siguiente paso.<\/p>\n\n<p>\u00abPara la gram\u00e1tica, les hago leer la frase o se turnan para leer frases si es demasiado para ellos. Intento que hagan la mayor parte del trabajo gui\u00e1ndoles yo si al principio no captan un concepto\u00bb.<\/p>\n\n<p>Ed emplea este enfoque con la vista puesta en los beneficios que reporta a largo plazo.<\/p>\n\n<p>\u00abEspero que los alumnos aprendan buenos h\u00e1bitos y cimientos en KidWorks para labrarse un futuro mejor\u00bb, afirma. \u00abEspero que KidWorks siga siendo una organizaci\u00f3n impulsada por la comunidad y su misi\u00f3n, que ayude a los j\u00f3venes a crecer y a tener un sentimiento de pertenencia y que permita a los padres implicarse en el desarrollo de sus hijos e hijas.\u00bb<\/p>\n\n<p>Mientras Ed da los siguientes pasos en su carrera de medicina, podemos dar fe de primera mano de su profunda atenci\u00f3n y compasi\u00f3n por los dem\u00e1s. Nos sentimos honrados de que haya elegido KidWorks como lugar para compartir su persona.<\/p>\n\n<p><em>Por Glenn Leibowitz, escritor voluntario<\/em><em><\/em><\/p>\n\n<p><strong><em>Invitamos a los estudiantes de bachillerato y universitarios a informarse sobre c\u00f3mo KidWorks puede ofrecerles oportunidades para ganar horas de servicio, realizar pr\u00e1cticas y ser voluntarios.<\/em><\/strong><\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/kidworksoc.org\/volunteer\/\">saber m\u00e1s<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos de segundo curso de los programas extraescolares de KidWorks saben que Ed Duong, nuestro \u00abVoluntario del mes\u00bb de febrero de 2024, es el tipo al que acudir cuando&hellip; <a class=\"more-link\" href=\"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/\">Siga Leyendo<\/a><\/p>\n","protected":false},"author":10,"featured_media":4962,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[67],"tags":[108],"class_list":["post-5041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voluntario-del-mes","tag-volunteers-es"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Febrero 2024 &#039;Voluntario del Mes&#039;: Ed Duong - KidWorks<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Febrero 2024 &#039;Voluntario del Mes&#039;: Ed Duong - KidWorks\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/\" \/>\n<meta property=\"og:site_name\" content=\"KidWorks\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kidworkscdc\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-01T21:43:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-06T23:59:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1903-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"KidWorks Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@kidworks\" \/>\n<meta name=\"twitter:site\" content=\"@kidworks\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/febrero-2024-voluntario-del-mes-ed-duong\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/febrero-2024-voluntario-del-mes-ed-duong\\\/\"},\"author\":{\"name\":\"KidWorks Marketing\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#\\\/schema\\\/person\\\/a7ea8668fb945e600fed3888df5f8687\"},\"headline\":\"Febrero 2024 &#8216;Voluntario del Mes&#8217;: Ed Duong\",\"datePublished\":\"2024-02-01T21:43:47+00:00\",\"dateModified\":\"2024-02-06T23:59:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/febrero-2024-voluntario-del-mes-ed-duong\\\/\"},\"wordCount\":779,\"publisher\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/febrero-2024-voluntario-del-mes-ed-duong\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_1903-scaled.jpg\",\"keywords\":[\"Volunteers\"],\"articleSection\":[\"Voluntario del mes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/febrero-2024-voluntario-del-mes-ed-duong\\\/\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/febrero-2024-voluntario-del-mes-ed-duong\\\/\",\"name\":\"Febrero 2024 'Voluntario del Mes': Ed Duong - KidWorks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/febrero-2024-voluntario-del-mes-ed-duong\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/febrero-2024-voluntario-del-mes-ed-duong\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_1903-scaled.jpg\",\"datePublished\":\"2024-02-01T21:43:47+00:00\",\"dateModified\":\"2024-02-06T23:59:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/febrero-2024-voluntario-del-mes-ed-duong\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kidworksoc.org\\\/es\\\/febrero-2024-voluntario-del-mes-ed-duong\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/febrero-2024-voluntario-del-mes-ed-duong\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_1903-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_1903-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/febrero-2024-voluntario-del-mes-ed-duong\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Febrero 2024 &#8216;Voluntario del Mes&#8217;: Ed Duong\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\",\"name\":\"KidWorks\",\"description\":\"Unleashing Youth Potential\u2122\",\"publisher\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#organization\",\"name\":\"KidWorks\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/kidworks-anniversary-logo.png\",\"contentUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/kidworks-anniversary-logo.png\",\"width\":420,\"height\":114,\"caption\":\"KidWorks\"},\"image\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kidworkscdc\",\"https:\\\/\\\/x.com\\\/kidworks\",\"https:\\\/\\\/www.instagram.com\\\/kidworks\\\/\",\"https:\\\/\\\/www.yelp.com\\\/biz\\\/kidworks-santa-ana?osq=kidworks\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/KidWorksCDC\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kidworkscdc\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#\\\/schema\\\/person\\\/a7ea8668fb945e600fed3888df5f8687\",\"name\":\"KidWorks Marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e9a2d51d39bbb8c77e752f6c9bf19e0b0d5aee87e0f69f70153c69ab97f31d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e9a2d51d39bbb8c77e752f6c9bf19e0b0d5aee87e0f69f70153c69ab97f31d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e9a2d51d39bbb8c77e752f6c9bf19e0b0d5aee87e0f69f70153c69ab97f31d9?s=96&d=mm&r=g\",\"caption\":\"KidWorks Marketing\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Febrero 2024 'Voluntario del Mes': Ed Duong - KidWorks","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/","og_locale":"es_ES","og_type":"article","og_title":"Febrero 2024 'Voluntario del Mes': Ed Duong - KidWorks","og_url":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/","og_site_name":"KidWorks","article_publisher":"https:\/\/www.facebook.com\/kidworkscdc","article_published_time":"2024-02-01T21:43:47+00:00","article_modified_time":"2024-02-06T23:59:09+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1903-scaled.jpg","type":"image\/jpeg"}],"author":"KidWorks Marketing","twitter_card":"summary_large_image","twitter_creator":"@kidworks","twitter_site":"@kidworks","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/#article","isPartOf":{"@id":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/"},"author":{"name":"KidWorks Marketing","@id":"https:\/\/kidworksoc.org\/es\/#\/schema\/person\/a7ea8668fb945e600fed3888df5f8687"},"headline":"Febrero 2024 &#8216;Voluntario del Mes&#8217;: Ed Duong","datePublished":"2024-02-01T21:43:47+00:00","dateModified":"2024-02-06T23:59:09+00:00","mainEntityOfPage":{"@id":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/"},"wordCount":779,"publisher":{"@id":"https:\/\/kidworksoc.org\/es\/#organization"},"image":{"@id":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/#primaryimage"},"thumbnailUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1903-scaled.jpg","keywords":["Volunteers"],"articleSection":["Voluntario del mes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/","url":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/","name":"Febrero 2024 'Voluntario del Mes': Ed Duong - KidWorks","isPartOf":{"@id":"https:\/\/kidworksoc.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/#primaryimage"},"image":{"@id":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/#primaryimage"},"thumbnailUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1903-scaled.jpg","datePublished":"2024-02-01T21:43:47+00:00","dateModified":"2024-02-06T23:59:09+00:00","breadcrumb":{"@id":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/#primaryimage","url":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1903-scaled.jpg","contentUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2024\/02\/IMG_1903-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/kidworksoc.org\/es\/febrero-2024-voluntario-del-mes-ed-duong\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kidworksoc.org\/es\/"},{"@type":"ListItem","position":2,"name":"Febrero 2024 &#8216;Voluntario del Mes&#8217;: Ed Duong"}]},{"@type":"WebSite","@id":"https:\/\/kidworksoc.org\/es\/#website","url":"https:\/\/kidworksoc.org\/es\/","name":"KidWorks","description":"Unleashing Youth Potential\u2122","publisher":{"@id":"https:\/\/kidworksoc.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kidworksoc.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kidworksoc.org\/es\/#organization","name":"KidWorks","url":"https:\/\/kidworksoc.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kidworksoc.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/01\/kidworks-anniversary-logo.png","contentUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/01\/kidworks-anniversary-logo.png","width":420,"height":114,"caption":"KidWorks"},"image":{"@id":"https:\/\/kidworksoc.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kidworkscdc","https:\/\/x.com\/kidworks","https:\/\/www.instagram.com\/kidworks\/","https:\/\/www.yelp.com\/biz\/kidworks-santa-ana?osq=kidworks","https:\/\/www.youtube.com\/user\/KidWorksCDC","https:\/\/www.linkedin.com\/company\/kidworkscdc"]},{"@type":"Person","@id":"https:\/\/kidworksoc.org\/es\/#\/schema\/person\/a7ea8668fb945e600fed3888df5f8687","name":"KidWorks Marketing","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8e9a2d51d39bbb8c77e752f6c9bf19e0b0d5aee87e0f69f70153c69ab97f31d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8e9a2d51d39bbb8c77e752f6c9bf19e0b0d5aee87e0f69f70153c69ab97f31d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8e9a2d51d39bbb8c77e752f6c9bf19e0b0d5aee87e0f69f70153c69ab97f31d9?s=96&d=mm&r=g","caption":"KidWorks Marketing"}}]}},"_links":{"self":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/posts\/5041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/comments?post=5041"}],"version-history":[{"count":1,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/posts\/5041\/revisions"}],"predecessor-version":[{"id":5042,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/posts\/5041\/revisions\/5042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/media\/4962"}],"wp:attachment":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/media?parent=5041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/categories?post=5041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/tags?post=5041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}