{"id":3460,"date":"2022-10-12T10:42:00","date_gmt":"2022-10-12T17:42:00","guid":{"rendered":"http:\/\/kidworksoc.org\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/"},"modified":"2023-08-08T14:41:16","modified_gmt":"2023-08-08T21:41:16","slug":"oportunidades-de-asociacion-corporativa-con-kidworks-2","status":"publish","type":"post","link":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/","title":{"rendered":"Oportunidades de asociaci\u00f3n corporativa con KidWorks"},"content":{"rendered":"\n<p>Existen literalmente docenas de formas en las que las empresas y sus empleados pueden disfrutar de la experiencia KidWorks a la vez que fomentan el trabajo en equipo, la moral de los empleados y la reputaci\u00f3n de su organizaci\u00f3n en las comunidades en las que opera.<\/p>\n\n<p>Aunque KidWorks siempre agradece la ayuda econ\u00f3mica y las subvenciones, los voluntarios han sido realmente la fuerza motriz positiva de nuestros programas y de los cientos de estudiantes que se benefician de ellos.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Pr\u00f3ximos eventos especiales<\/strong><\/h3>\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>31 de octubre <\/strong><em>Truco o trato (K-12)<\/em><br\/><strong>Oct 31 |<\/strong><em>Fiesta de la Cosecha (Preescolar)<\/em><br\/><strong>Nov 17 |<\/strong><em>Fiesta de Acci\u00f3n de Gracias (Preescolar)<\/em><br\/><strong>Nov 21 | <\/strong><em>Copa del Pavo Juvenil<\/em><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>22 de noviembre <\/strong><em>Fiesta de Acci\u00f3n de Gracias<\/em><br\/><strong>Nov 23 | <\/strong>Decoraci\u00f3n navide\u00f1a de KidWorks<br\/><strong>8 de diciembre <\/strong><em>Celebraci\u00f3n navide\u00f1a de la AEP<\/em><br\/><strong>14 y 15 de diciembre <\/strong><em>Tienda de Navidad<\/em><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>Feb 17 &amp; 18 | <\/strong><em>Encierro de Friendentines<\/em><br\/><strong>3 de marzo <\/strong><em>D\u00eda de la Carrera Profesional<\/em><\/p>\n<\/div>\n<\/div>\n\n<p class=\"has-text-align-center\">Perfecto para empresas y departamentos para fomentar el esp\u00edritu de equipo y escapar de la oficina y divertirse.<\/p>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link wp-element-button\" href=\"http:\/\/kidworksoc.org\/es\/nuestros-socios\/\">Aprender M\u00e1s<\/a><\/div>\n<\/div>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"http:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/66bc7268-abdb-df06-808e-3fe96e873520.jpg\" alt=\"\" class=\"wp-image-2033\" srcset=\"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/66bc7268-abdb-df06-808e-3fe96e873520.jpg 300w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/66bc7268-abdb-df06-808e-3fe96e873520-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\"><strong>Donar caramelos<\/strong><\/h3>\n\n\n\n<p>Ayude a crear un Halloween \u00abSpooktacular\u00bb en KidWorks este oto\u00f1o. KidWorks est\u00e1 recogiendo caramelos para nuestro 5\u00ba Trunk-or-Treat anual. Visite el siguiente enlace para consultar nuestra lista de caramelos necesarios. Corre la voz compartiendo la lista con tu equipo. Los dulces pueden entregarse o enviarse directamente a KidWorks.<\/p>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"300\" height=\"225\" src=\"http:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/8e08fe41-ef19-2f55-666d-51fcd6ff1343.jpg\" alt=\"\" class=\"wp-image-2035\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\"><strong><strong><strong>Campa\u00f1a de recogida de juguetes<\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p>Cada a\u00f1o confiamos en la generosidad de nuestros socios para recoger m\u00e1s de 1.500 regalos. Su donaci\u00f3n de juguetes se utilizar\u00e1 para abastecer nuestra Tienda de Navidad, de modo que los padres puedan proporcionar unas Navidades alegres a sus hijos. Los juguetes pueden entregarse o enviarse directamente a KidWorks antes del <strong>9 de diciembre.<\/strong><\/p>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"300\" height=\"224\" src=\"http:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/e40879f3-d38d-213d-8408-b3be38c18415.png\" alt=\"\" class=\"wp-image-2037\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\"><strong><strong><strong><strong>Tienda de Navidad<\/strong><\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p>Ay\u00fadenos a repartir alegr\u00eda navide\u00f1a los <strong>d\u00edas 14 y 15 de diciembre<\/strong> entre los alumnos y las familias de KidWorks. Para llevar a cabo la Tienda de Navidad, necesitamos voluntarios para el montaje, el envoltorio de regalos y mucho m\u00e1s.<\/p>\n<\/div>\n<\/div>\n\n<h3 class=\"has-text-align-left wp-block-heading\"><strong>Las empresas y sus empleados pueden colaborar con KidWorks de las siguientes maneras:<\/strong><\/h3>\n\n<ul class=\"is-style-check-mark wp-block-list\">\n<li>Tutor\u00eda en nuestros programas extraescolares.<\/li>\n\n\n\n<li>Dirigir talleres de la Universidad KidWorks en los que los empleados de las empresas locales compartan una habilidad, talento o pasi\u00f3n. Estos talleres ayudan a nuestros alumnos a descubrir sus propias pasiones y talentos. Los talleres pueden centrarse en arte, ciencia, m\u00fasica, danza, escritura creativa, etc.<\/li>\n\n\n\n<li>Jornadas de orientaci\u00f3n profesional: Se invita a los trabajadores a compartir sus experiencias profesionales y laborales con nuestros estudiantes. Nuestros estudiantes cuentan a menudo que quienes compartieron con ellos sus experiencias laborales y profesionales les ayudaron a identificar una carrera o una pasi\u00f3n que de otro modo no habr\u00edan conocido.<\/li>\n<\/ul>\n\n<p class=\"has-text-align-center\"><strong><em>Obtenga m\u00e1s informaci\u00f3n sobre las formas en que su empresa y los miembros de su equipo pueden disfrutar de la experiencia KidWorks y asociarse con nosotros.<\/em><\/strong><\/p>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"http:\/\/kidworksoc.org\/es\/nuestros-socios\/\">Asociarse con KidWorks<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Existen literalmente docenas de formas en las que las empresas y sus empleados pueden disfrutar de la experiencia KidWorks a la vez que fomentan el trabajo en equipo, la moral&hellip; <a class=\"more-link\" href=\"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/\">Siga Leyendo<\/a><\/p>\n","protected":false},"author":6,"featured_media":734,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[133,100,132],"tags":[],"class_list":["post-3460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asociacion","category-eventos","category-fundacion-para-el-exito"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oportunidades de asociaci\u00f3n corporativa con KidWorks - KidWorks<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oportunidades de asociaci\u00f3n corporativa con KidWorks - KidWorks\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/\" \/>\n<meta property=\"og:site_name\" content=\"KidWorks\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kidworkscdc\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-12T17:42:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-08T21:41:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kidworksoc.org\/wp-content\/uploads\/2022\/12\/9c870f5a262681257f5717f9dd2c0bbc7727c580.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"KidWorks\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@kidworks\" \/>\n<meta name=\"twitter:site\" content=\"@kidworks\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/oportunidades-de-asociacion-corporativa-con-kidworks-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/oportunidades-de-asociacion-corporativa-con-kidworks-2\\\/\"},\"author\":{\"name\":\"KidWorks\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#\\\/schema\\\/person\\\/40aff51dce0455fa99956e12499c3879\"},\"headline\":\"Oportunidades de asociaci\u00f3n corporativa con KidWorks\",\"datePublished\":\"2022-10-12T17:42:00+00:00\",\"dateModified\":\"2023-08-08T21:41:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/oportunidades-de-asociacion-corporativa-con-kidworks-2\\\/\"},\"wordCount\":491,\"publisher\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/oportunidades-de-asociacion-corporativa-con-kidworks-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/9c870f5a262681257f5717f9dd2c0bbc7727c580.jpg\",\"articleSection\":[\"Asociaci\u00f3n\",\"Eventos\",\"Fundaci\u00f3n para el \u00e9xito\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/oportunidades-de-asociacion-corporativa-con-kidworks-2\\\/\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/oportunidades-de-asociacion-corporativa-con-kidworks-2\\\/\",\"name\":\"Oportunidades de asociaci\u00f3n corporativa con KidWorks - KidWorks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/oportunidades-de-asociacion-corporativa-con-kidworks-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/oportunidades-de-asociacion-corporativa-con-kidworks-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/9c870f5a262681257f5717f9dd2c0bbc7727c580.jpg\",\"datePublished\":\"2022-10-12T17:42:00+00:00\",\"dateModified\":\"2023-08-08T21:41:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/oportunidades-de-asociacion-corporativa-con-kidworks-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kidworksoc.org\\\/es\\\/oportunidades-de-asociacion-corporativa-con-kidworks-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/oportunidades-de-asociacion-corporativa-con-kidworks-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/9c870f5a262681257f5717f9dd2c0bbc7727c580.jpg\",\"contentUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/9c870f5a262681257f5717f9dd2c0bbc7727c580.jpg\",\"width\":500,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/oportunidades-de-asociacion-corporativa-con-kidworks-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oportunidades de asociaci\u00f3n corporativa con KidWorks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\",\"name\":\"KidWorks\",\"description\":\"Unleashing Youth Potential\u2122\",\"publisher\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#organization\",\"name\":\"KidWorks\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/kidworks-anniversary-logo.png\",\"contentUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/kidworks-anniversary-logo.png\",\"width\":420,\"height\":114,\"caption\":\"KidWorks\"},\"image\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kidworkscdc\",\"https:\\\/\\\/x.com\\\/kidworks\",\"https:\\\/\\\/www.instagram.com\\\/kidworks\\\/\",\"https:\\\/\\\/www.yelp.com\\\/biz\\\/kidworks-santa-ana?osq=kidworks\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/KidWorksCDC\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kidworkscdc\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#\\\/schema\\\/person\\\/40aff51dce0455fa99956e12499c3879\",\"name\":\"KidWorks\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a64e155874bd3cc9526dca85d2e8b2d22f147e94203fd25c5fa18e2f2e7a0e51?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a64e155874bd3cc9526dca85d2e8b2d22f147e94203fd25c5fa18e2f2e7a0e51?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a64e155874bd3cc9526dca85d2e8b2d22f147e94203fd25c5fa18e2f2e7a0e51?s=96&d=mm&r=g\",\"caption\":\"KidWorks\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oportunidades de asociaci\u00f3n corporativa con KidWorks - KidWorks","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/","og_locale":"es_ES","og_type":"article","og_title":"Oportunidades de asociaci\u00f3n corporativa con KidWorks - KidWorks","og_url":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/","og_site_name":"KidWorks","article_publisher":"https:\/\/www.facebook.com\/kidworkscdc","article_published_time":"2022-10-12T17:42:00+00:00","article_modified_time":"2023-08-08T21:41:16+00:00","og_image":[{"width":500,"height":667,"url":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2022\/12\/9c870f5a262681257f5717f9dd2c0bbc7727c580.jpg","type":"image\/jpeg"}],"author":"KidWorks","twitter_card":"summary_large_image","twitter_creator":"@kidworks","twitter_site":"@kidworks","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/#article","isPartOf":{"@id":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/"},"author":{"name":"KidWorks","@id":"https:\/\/kidworksoc.org\/es\/#\/schema\/person\/40aff51dce0455fa99956e12499c3879"},"headline":"Oportunidades de asociaci\u00f3n corporativa con KidWorks","datePublished":"2022-10-12T17:42:00+00:00","dateModified":"2023-08-08T21:41:16+00:00","mainEntityOfPage":{"@id":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/"},"wordCount":491,"publisher":{"@id":"https:\/\/kidworksoc.org\/es\/#organization"},"image":{"@id":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/#primaryimage"},"thumbnailUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2022\/12\/9c870f5a262681257f5717f9dd2c0bbc7727c580.jpg","articleSection":["Asociaci\u00f3n","Eventos","Fundaci\u00f3n para el \u00e9xito"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/","url":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/","name":"Oportunidades de asociaci\u00f3n corporativa con KidWorks - KidWorks","isPartOf":{"@id":"https:\/\/kidworksoc.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/#primaryimage"},"image":{"@id":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/#primaryimage"},"thumbnailUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2022\/12\/9c870f5a262681257f5717f9dd2c0bbc7727c580.jpg","datePublished":"2022-10-12T17:42:00+00:00","dateModified":"2023-08-08T21:41:16+00:00","breadcrumb":{"@id":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/#primaryimage","url":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2022\/12\/9c870f5a262681257f5717f9dd2c0bbc7727c580.jpg","contentUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2022\/12\/9c870f5a262681257f5717f9dd2c0bbc7727c580.jpg","width":500,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/kidworksoc.org\/es\/oportunidades-de-asociacion-corporativa-con-kidworks-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kidworksoc.org\/es\/"},{"@type":"ListItem","position":2,"name":"Oportunidades de asociaci\u00f3n corporativa con KidWorks"}]},{"@type":"WebSite","@id":"https:\/\/kidworksoc.org\/es\/#website","url":"https:\/\/kidworksoc.org\/es\/","name":"KidWorks","description":"Unleashing Youth Potential\u2122","publisher":{"@id":"https:\/\/kidworksoc.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kidworksoc.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kidworksoc.org\/es\/#organization","name":"KidWorks","url":"https:\/\/kidworksoc.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kidworksoc.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/01\/kidworks-anniversary-logo.png","contentUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/01\/kidworks-anniversary-logo.png","width":420,"height":114,"caption":"KidWorks"},"image":{"@id":"https:\/\/kidworksoc.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kidworkscdc","https:\/\/x.com\/kidworks","https:\/\/www.instagram.com\/kidworks\/","https:\/\/www.yelp.com\/biz\/kidworks-santa-ana?osq=kidworks","https:\/\/www.youtube.com\/user\/KidWorksCDC","https:\/\/www.linkedin.com\/company\/kidworkscdc"]},{"@type":"Person","@id":"https:\/\/kidworksoc.org\/es\/#\/schema\/person\/40aff51dce0455fa99956e12499c3879","name":"KidWorks","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a64e155874bd3cc9526dca85d2e8b2d22f147e94203fd25c5fa18e2f2e7a0e51?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a64e155874bd3cc9526dca85d2e8b2d22f147e94203fd25c5fa18e2f2e7a0e51?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a64e155874bd3cc9526dca85d2e8b2d22f147e94203fd25c5fa18e2f2e7a0e51?s=96&d=mm&r=g","caption":"KidWorks"}}]}},"_links":{"self":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/posts\/3460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/comments?post=3460"}],"version-history":[{"count":0,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/posts\/3460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/media\/734"}],"wp:attachment":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/media?parent=3460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/categories?post=3460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/tags?post=3460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}