{"id":3172,"date":"2023-01-25T11:03:04","date_gmt":"2023-01-25T19:03:04","guid":{"rendered":"http:\/\/kidworksoc.org\/grupos-socios\/"},"modified":"2023-07-13T10:28:43","modified_gmt":"2023-07-13T17:28:43","slug":"grupos-socios","status":"publish","type":"page","link":"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/","title":{"rendered":"Grupos\/Socios"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light\" style=\"padding-top:var(--wp--preset--spacing--300);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--150);padding-left:var(--wp--preset--spacing--30)\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-100 has-background-dim has-background-gradient\" style=\"background:linear-gradient(0deg,rgb(0,28,74) 0%,rgba(0,28,74,0.35) 100%)\"><\/span><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_9885.jpg\" class=\"wp-block-cover__image-background wp-post-image\" alt=\"\" data-object-fit=\"cover\" srcset=\"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_9885.jpg 2000w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_9885-1280x853.jpg 1280w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_9885-1600x1066.jpg 1600w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_9885-1440x960.jpg 1440w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_9885-1536x1024.jpg 1536w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_9885-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-50da5a02 wp-block-group-is-layout-constrained\">\n<h1 class=\"wp-block-heading has-text-align-center has-white-color has-text-color\" style=\"font-size:clamp(33.419px, 2.089rem + ((1vw - 3.2px) * 2.769), 60px);\"><strong>Grupos\/Socios<\/strong><\/h1>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-medium-font-size\">KidWorks ofrece <strong>oportunidades significativas<\/strong> para que <strong>empresas,<\/strong> <strong>iglesias<\/strong> y <strong>grupos c\u00edvicos<\/strong> se asocien con nuestros alumnos.<\/p>\n\n\n\n<div class=\"wp-block-buttons alignwide is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-7878cfa4 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-secondary-btn\"><a class=\"wp-block-button__link wp-element-button\" href=\"http:\/\/kidworksoc.org\/es\/in-kind\/\">Solicitudes en especie<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-secondary-btn\"><a class=\"wp-block-button__link wp-element-button\" href=\"http:\/\/kidworksoc.org\/es\/jovenes-profesionales\/\">J\u00f3venes profesionales<\/a><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-group alignfull has-tertiary-light-background-color has-background has-global-padding is-layout-constrained wp-container-core-group-is-layout-9629f533 wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--100);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--100);padding-left:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Regalos de contrapartida<\/strong><\/h3>\n\n\n\n<p>Muchas empresas ofrecen un programa de subvenciones al voluntariado de los empleados para fomentar la filantrop\u00eda entre sus empleados. A trav\u00e9s de estos programas, las empresas conceden subvenciones monetarias a organizaciones en las que los empleados prestan servicio voluntario con regularidad.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link wp-element-button\" href=\"http:\/\/kidworksoc.org\/es\/regalos-de-contrapartida\/\">Aprender M\u00e1s<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Log\u00edstica de grupos de voluntarios<\/strong><\/h3>\n\n\n\n<p>All volunteer shifts will be reserved on a first-come, first-serve basis. Cancellations will need to be made a week in advance, so we can search for replacement volunteers.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Tama\u00f1o del grupo<\/strong><\/h3>\n\n\n\n<p>5 &#8211; 10 voluntarios<\/p>\n\n\n\n<p><em>Si desea acomodar a un grupo m\u00e1s grande, puede dividirlo en diferentes sesiones. Por ejemplo, puede programar 10 voluntarios para la sesi\u00f3n de 14.45 a 16.00 horas y otros 10 voluntarios para la sesi\u00f3n de 16.00 a 17.00 horas.<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<div style=\"height:42px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center\"><strong>\u00bfPreguntas?<\/strong><br\/>Si desea reservar alg\u00fan turno de voluntariado para su equipo y\/o si tiene alguna pregunta, p\u00f3ngase en contacto conmigo en mi correo electr\u00f3nico o en el n\u00famero que figura m\u00e1s abajo. Estamos deseando tenerle a bordo.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Env\u00ede un correo electr\u00f3nico <a href=\"mailto:vanessa@kidworksoc.org\" target=\"_blank\" rel=\"noreferrer noopener\">a vanessa@kidworksoc.org<\/a> para obtener m\u00e1s informaci\u00f3n e inscribirse como voluntario.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div  class=\"tribe-compatibility-container\" >\n\t<div\n\t\t class=\"tribe-common tribe-events tribe-events-view tribe-events-view--widget-events-list tribe-events-widget\" \t\tdata-js=\"tribe-events-view\"\n\t\tdata-view-rest-url=\"https:\/\/kidworksoc.org\/es\/wp-json\/tribe\/views\/v2\/html\"\n\t\tdata-view-manage-url=\"1\"\n\t\t\t\t\t\t\tdata-view-breakpoint-pointer=\"8ac09d2d-e47b-4bee-ae53-aefd1b2f1018\"\n\t\t\t>\n\t\t<div class=\"tribe-events-widget-events-list\">\n\n\t\t\t\n\t\t\t<script data-js=\"tribe-events-view-data\" type=\"application\/json\">\n\t{\"slug\":\"widget-events-list\",\"prev_url\":\"\",\"next_url\":\"\",\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Widgets\\\\Widget_List_View\",\"view_slug\":\"widget-events-list\",\"view_label\":\"View\",\"view\":null,\"should_manage_url\":true,\"id\":null,\"alias-slugs\":null,\"title\":\"Pr\\u00f3ximos Eventos \\u2013 KidWorks\",\"limit\":\"4\",\"no_upcoming_events\":false,\"featured_events_only\":false,\"jsonld_enable\":true,\"tribe_is_list_widget\":false,\"admin_fields\":{\"title\":{\"label\":\"T\\u00edtulo:\",\"type\":\"text\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-title\",\"name\":\"widget-tribe-widget-events-list[-1][title]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"limit\":{\"label\":\"Mostrar:\",\"type\":\"number\",\"default\":5,\"min\":1,\"max\":10,\"step\":1,\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-limit\",\"name\":\"widget-tribe-widget-events-list[-1][limit]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"metadata_section\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-checkbox-group\",\"label\":\"Mostrar:\",\"children\":{\"cost\":{\"type\":\"checkbox\",\"label\":\"Price\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-cost\",\"name\":\"widget-tribe-widget-events-list[-1][cost]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"venue\":{\"type\":\"checkbox\",\"label\":\"Venue\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-venue\",\"name\":\"widget-tribe-widget-events-list[-1][venue]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"street\":{\"type\":\"checkbox\",\"label\":\"Street\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-street\",\"name\":\"widget-tribe-widget-events-list[-1][street]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"city\":{\"type\":\"checkbox\",\"label\":\"City\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-city\",\"name\":\"widget-tribe-widget-events-list[-1][city]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"region\":{\"type\":\"checkbox\",\"label\":\"State (US) Or Province (Int)\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-region\",\"name\":\"widget-tribe-widget-events-list[-1][region]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"zip\":{\"type\":\"checkbox\",\"label\":\"Postal Code\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-zip\",\"name\":\"widget-tribe-widget-events-list[-1][zip]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"country\":{\"type\":\"checkbox\",\"label\":\"Country\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-country\",\"name\":\"widget-tribe-widget-events-list[-1][country]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"phone\":{\"type\":\"checkbox\",\"label\":\"Phone\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-phone\",\"name\":\"widget-tribe-widget-events-list[-1][phone]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"organizer\":{\"type\":\"checkbox\",\"label\":\"Organizer\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-organizer\",\"name\":\"widget-tribe-widget-events-list[-1][organizer]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"website\":{\"type\":\"checkbox\",\"label\":\"Web\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-website\",\"name\":\"widget-tribe-widget-events-list[-1][website]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-metadata_section\",\"name\":\"widget-tribe-widget-events-list[-1][metadata_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy_section\":{\"type\":\"section\",\"classes\":[\"calendar-widget-filters-container\"],\"label\":\"Filtros:\",\"children\":{\"filters\":{\"type\":\"taxonomy-filters\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-filters\",\"label\":\"\",\"name\":\"widget-tribe-widget-events-list[-1][filters]\",\"options\":[],\"placeholder\":\"\",\"value\":null,\"list_items\":[]},\"operand\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-radio-group\",\"label\":\"Operand:\",\"selected\":\"OR\",\"children\":[{\"type\":\"radio\",\"label\":\"Match any\",\"button_value\":\"OR\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-operand\",\"name\":\"widget-tribe-widget-events-list[-1][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null},{\"type\":\"radio\",\"label\":\"Match all\",\"button_value\":\"AND\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-operand\",\"name\":\"widget-tribe-widget-events-list[-1][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}],\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-operand\",\"name\":\"widget-tribe-widget-events-list[-1][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-taxonomy_section\",\"name\":\"widget-tribe-widget-events-list[-1][taxonomy_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy\":{\"type\":\"taxonomy\",\"classes\":\"calendar-widget-add-filter\",\"label\":\"Agregar un filtro:\",\"placeholder\":\"Select a Taxonomy Term\",\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-taxonomy\",\"name\":\"widget-tribe-widget-events-list[-1][taxonomy]\",\"options\":[],\"value\":null},\"no_upcoming_events\":{\"label\":\"Ocultar este widget si no hay pr\\u00f3ximos eventos.\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-no_upcoming_events\",\"name\":\"widget-tribe-widget-events-list[-1][no_upcoming_events]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"featured_events_only\":{\"label\":\"Limitar a solo eventos destacados\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-featured_events_only\",\"name\":\"widget-tribe-widget-events-list[-1][featured_events_only]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"jsonld_enable\":{\"label\":\"Generar datos JSON-LD\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-jsonld_enable\",\"name\":\"widget-tribe-widget-events-list[-1][jsonld_enable]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"venue\":false,\"country\":false,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"phone\":false,\"cost\":false,\"organizer\":false,\"website\":false,\"operand\":\"OR\",\"filters\":\"{\\\"post_tag\\\":[\\\"70\\\"]}\",\"events\":[],\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/?post_type=tribe_events&eventDisplay=widget-events-list&tag=70\",\"url_event_date\":false,\"bar\":{\"keyword\":\"\",\"date\":\"\"},\"today\":\"2026-05-13 00:00:00\",\"now\":\"2026-05-13 07:58:18\",\"home_url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\",\"rest_url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/wp-json\\\/tribe\\\/views\\\/v2\\\/html\",\"rest_method\":\"GET\",\"rest_nonce\":\"\",\"today_url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/?post_type=tribe_events&eventDisplay=widget-events-list&tag=70&rest_route=%2Fwp%2Fv2%2Fpages%2F3172\",\"today_title\":\"Haz clic para seleccionar la fecha de hoy\",\"today_label\":\"Hoy\",\"prev_label\":\"\",\"next_label\":\"\",\"date_formats\":{\"compact\":\"n\\\/j\\\/Y\",\"month_and_year_compact\":\"n\\\/Y\",\"month_and_year\":\"F Y\",\"time_range_separator\":\" - \",\"date_time_separator\":\" @ \"},\"messages\":{\"notice\":[\"No hay eventos programados.\"]},\"start_of_week\":\"0\",\"header_title\":\"\",\"header_title_element\":\"h1\",\"content_title\":\"\",\"show_content_title\":false,\"breadcrumbs\":[],\"backlink\":false,\"before_events\":\"\",\"after_events\":\"\\n<!--\\nThis calendar is powered by The Events Calendar.\\nhttp:\\\/\\\/evnt.is\\\/18wn\\n-->\\n\",\"display_events_bar\":false,\"disable_event_search\":false,\"live_refresh\":true,\"ical\":{\"display_link\":true,\"link\":{\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/?post_type=tribe_events&#038;eventDisplay=widget-events-list&#038;tag=70&#038;ical=1\",\"text\":\"Exportar Eventos\",\"title\":\"Usa esto para compartir los datos del calendario con Google Calendar, Apple iCal y otras aplicaciones compatibles\"}},\"container_classes\":[\"tribe-common\",\"tribe-events\",\"tribe-events-view\",\"tribe-events-view--widget-events-list\",\"tribe-events-widget\"],\"container_data\":[],\"is_past\":false,\"breakpoints\":{\"xsmall\":500,\"medium\":768,\"full\":960},\"breakpoint_pointer\":\"8ac09d2d-e47b-4bee-ae53-aefd1b2f1018\",\"is_initial_load\":false,\"public_views\":{\"list\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\List_View\",\"view_url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/eventos\\\/etiqueta\\\/(%5B\\\/%5D+)\\\/lista\\\/\",\"view_label\":\"Lista\",\"aria_label\":\"Mostrar Eventos en la vista Lista\"},\"month\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Month_View\",\"view_url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/eventos\\\/etiqueta\\\/(%5B\\\/%5D+)\\\/mes\\\/\",\"view_label\":\"Mes\",\"aria_label\":\"Mostrar Eventos en la vista Mes\"}},\"show_latest_past\":false,\"past\":false,\"category_colors_enabled\":false,\"category_colors_category_dropdown\":[],\"category_colors_super_power\":false,\"category_colors_show_reset_button\":false,\"compatibility_classes\":[\"tribe-compatibility-container\"],\"view_more_text\":\"Ver calendario\",\"view_more_title\":\"Ver m\\u00e1s eventos.\",\"view_more_link\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/eventos\\\/\",\"widget_title\":\"Upcoming Events\",\"hide_if_no_upcoming_events\":false,\"display\":{\"cost\":false,\"venue\":false,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"country\":false,\"phone\":false,\"organizer\":false,\"website\":false},\"subscribe_links\":{\"gcal\":{\"label\":\"Google Calendar\",\"single_label\":\"A\\u00f1adir a Google Calendar\",\"visible\":true,\"block_slug\":\"hasGoogleCalendar\"},\"ical\":{\"label\":\"iCalendar\",\"single_label\":\"Agregar a iCalendar\",\"visible\":true,\"block_slug\":\"hasiCal\"},\"outlook-365\":{\"label\":\"Outlook 365\",\"single_label\":\"Outlook 365\",\"visible\":true,\"block_slug\":\"hasOutlook365\"},\"outlook-live\":{\"label\":\"Outlook Live\",\"single_label\":\"Outlook Live\",\"visible\":true,\"block_slug\":\"hasOutlookLive\"},\"ics\":{\"label\":\"Exportar archivo .ics\",\"single_label\":\"Exportar archivo .ics\",\"visible\":true,\"block_slug\":null},\"outlook-ics\":{\"label\":\"Exportar archivo .ics de Outlook\",\"single_label\":\"Exportar archivo .ics de Outlook\",\"visible\":true,\"block_slug\":null}},\"display_recurring_toggle\":false,\"_context\":{\"slug\":\"widget-events-list\"}}<\/script>\n\n\t\t\t\t\t\t\t<header class=\"tribe-events-widget-events-list__header\">\n\t\t\t\t\t<h2 class=\"tribe-events-widget-events-list__header-title tribe-common-h6 tribe-common-h--alt\">\n\t\t\t\t\t\tUpcoming Events\t\t\t\t\t<\/h2>\n\t\t\t\t<\/header>\n\t\t\t\n\t\t\t\n\t\t\t\t<div  class=\"tribe-events-header__messages tribe-events-c-messages tribe-common-b2\"  >\n\t\t\t<div class=\"tribe-events-c-messages__message tribe-events-c-messages__message--notice\" tabindex=\"0\" role=\"alert\" aria-live=\"assertive\">\n\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--messages-not-found tribe-events-c-messages__message-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 21 23\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<g fill-rule=\"evenodd\">\n\t\t<path d=\"M.5 2.5h20v20H.5z\"\/>\n\t\t<path stroke-linecap=\"round\" d=\"M7.583 11.583l5.834 5.834m0-5.834l-5.834 5.834\" class=\"tribe-common-c-svgicon__svg-stroke\"\/>\n\t\t<path stroke-linecap=\"round\" d=\"M4.5.5v4m12-4v4\"\/>\n\t\t<path stroke-linecap=\"square\" d=\"M.5 7.5h20\"\/>\n\t<\/g>\n<\/svg>\n<span class=\"tribe-common-a11y-visual-hide\">\n\tAviso<\/span>\n\t\t\t\t\t\t\t<div\n\t\t\t\t\t data-key=\"0\" >\n\t\t\t\t\tNo hay eventos programados.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<script data-js='tribe-events-view-nonce-data' type='application\/json'>{\"tvn1\":\"9f4540a6c4\",\"tvn2\":\"\"}<\/script>\n<\/div>\n<\/div>\n\n<p class=\"has-text-align-center\"><\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1500\" height=\"615\" src=\"http:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_8719-2.jpg\" alt=\"\" class=\"wp-image-2518\" srcset=\"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_8719-2.jpg 1500w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_8719-2-1280x525.jpg 1280w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_8719-2-1440x590.jpg 1440w, https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_8719-2-600x246.jpg 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Regalos de contrapartida Muchas empresas ofrecen un programa de subvenciones al voluntariado de los empleados para fomentar la filantrop\u00eda entre sus empleados. A trav\u00e9s de estos programas, las empresas conceden&hellip; <a class=\"more-link\" href=\"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/\">Siga Leyendo<\/a><\/p>\n","protected":false},"author":1,"featured_media":2515,"parent":3173,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_searchwp_excluded":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-3172","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grupos\/Socios - KidWorks<\/title>\n<meta name=\"description\" content=\"Grupos\/Socios KidWorks ofrece oportunidades significativas para que empresas, iglesias y grupos c\u00edvicos se asocien con nuestros alumnos. Solicitudes en\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grupos\/Socios - KidWorks\" \/>\n<meta property=\"og:description\" content=\"Grupos\/Socios KidWorks ofrece oportunidades significativas para que empresas, iglesias y grupos c\u00edvicos se asocien con nuestros alumnos. Solicitudes en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/\" \/>\n<meta property=\"og:site_name\" content=\"KidWorks\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kidworkscdc\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-13T17:28:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_9885.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@kidworks\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/voluntario\\\/grupos-socios\\\/\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/voluntario\\\/grupos-socios\\\/\",\"name\":\"Grupos\\\/Socios - KidWorks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/voluntario\\\/grupos-socios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/voluntario\\\/grupos-socios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/IMG_9885.jpg\",\"datePublished\":\"2023-01-25T19:03:04+00:00\",\"dateModified\":\"2023-07-13T17:28:43+00:00\",\"description\":\"Grupos\\\/Socios KidWorks ofrece oportunidades significativas para que empresas, iglesias y grupos c\u00edvicos se asocien con nuestros alumnos. Solicitudes en\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/voluntario\\\/grupos-socios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kidworksoc.org\\\/es\\\/voluntario\\\/grupos-socios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/voluntario\\\/grupos-socios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/IMG_9885.jpg\",\"contentUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/IMG_9885.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/voluntario\\\/grupos-socios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voluntario\",\"item\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/voluntario\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grupos\\\/Socios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\",\"name\":\"KidWorks\",\"description\":\"Unleashing Youth Potential\u2122\",\"publisher\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#organization\",\"name\":\"KidWorks\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/kidworks-anniversary-logo.png\",\"contentUrl\":\"https:\\\/\\\/kidworksoc.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/kidworks-anniversary-logo.png\",\"width\":420,\"height\":114,\"caption\":\"KidWorks\"},\"image\":{\"@id\":\"https:\\\/\\\/kidworksoc.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kidworkscdc\",\"https:\\\/\\\/x.com\\\/kidworks\",\"https:\\\/\\\/www.instagram.com\\\/kidworks\\\/\",\"https:\\\/\\\/www.yelp.com\\\/biz\\\/kidworks-santa-ana?osq=kidworks\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/KidWorksCDC\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kidworkscdc\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grupos\/Socios - KidWorks","description":"Grupos\/Socios KidWorks ofrece oportunidades significativas para que empresas, iglesias y grupos c\u00edvicos se asocien con nuestros alumnos. Solicitudes en","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/","og_locale":"es_ES","og_type":"article","og_title":"Grupos\/Socios - KidWorks","og_description":"Grupos\/Socios KidWorks ofrece oportunidades significativas para que empresas, iglesias y grupos c\u00edvicos se asocien con nuestros alumnos. Solicitudes en","og_url":"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/","og_site_name":"KidWorks","article_publisher":"https:\/\/www.facebook.com\/kidworkscdc","article_modified_time":"2023-07-13T17:28:43+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_9885.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@kidworks","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/","url":"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/","name":"Grupos\/Socios - KidWorks","isPartOf":{"@id":"https:\/\/kidworksoc.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/#primaryimage"},"image":{"@id":"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/#primaryimage"},"thumbnailUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_9885.jpg","datePublished":"2023-01-25T19:03:04+00:00","dateModified":"2023-07-13T17:28:43+00:00","description":"Grupos\/Socios KidWorks ofrece oportunidades significativas para que empresas, iglesias y grupos c\u00edvicos se asocien con nuestros alumnos. Solicitudes en","breadcrumb":{"@id":"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/#primaryimage","url":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_9885.jpg","contentUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/02\/IMG_9885.jpg","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/kidworksoc.org\/es\/voluntario\/grupos-socios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kidworksoc.org\/es\/"},{"@type":"ListItem","position":2,"name":"Voluntario","item":"https:\/\/kidworksoc.org\/es\/voluntario\/"},{"@type":"ListItem","position":3,"name":"Grupos\/Socios"}]},{"@type":"WebSite","@id":"https:\/\/kidworksoc.org\/es\/#website","url":"https:\/\/kidworksoc.org\/es\/","name":"KidWorks","description":"Unleashing Youth Potential\u2122","publisher":{"@id":"https:\/\/kidworksoc.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kidworksoc.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kidworksoc.org\/es\/#organization","name":"KidWorks","url":"https:\/\/kidworksoc.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kidworksoc.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/01\/kidworks-anniversary-logo.png","contentUrl":"https:\/\/kidworksoc.org\/wp-content\/uploads\/2023\/01\/kidworks-anniversary-logo.png","width":420,"height":114,"caption":"KidWorks"},"image":{"@id":"https:\/\/kidworksoc.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kidworkscdc","https:\/\/x.com\/kidworks","https:\/\/www.instagram.com\/kidworks\/","https:\/\/www.yelp.com\/biz\/kidworks-santa-ana?osq=kidworks","https:\/\/www.youtube.com\/user\/KidWorksCDC","https:\/\/www.linkedin.com\/company\/kidworkscdc"]}]}},"_links":{"self":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/pages\/3172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/comments?post=3172"}],"version-history":[{"count":0,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/pages\/3172\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/pages\/3173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/media\/2515"}],"wp:attachment":[{"href":"https:\/\/kidworksoc.org\/es\/wp-json\/wp\/v2\/media?parent=3172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}